{"id":27089,"date":"2026-07-15T16:40:57","date_gmt":"2026-07-15T14:40:57","guid":{"rendered":"https:\/\/www.mk-journal.de\/?p=27089"},"modified":"2026-07-15T16:40:57","modified_gmt":"2026-07-15T14:40:57","slug":"grosseinsatz-bei-waldbrand","status":"publish","type":"post","link":"https:\/\/www.mk-journal.de\/index.php\/2026\/07\/15\/grosseinsatz-bei-waldbrand\/","title":{"rendered":"Gro\u00dfeinsatz bei Waldbrand"},"content":{"rendered":"<h4>Kreisbrandmeister: &#8222;Gute Vorbereitung hat sich ausgezahlt&#8220;<\/h4>\n<p>(pmk). Das anhaltend hei\u00dfe und trockene Wetter erh\u00f6ht die Waldbrandgefahr und stellt die Feuerwehr kreisweit vor gro\u00dfe Herausforderungen. Am Dienstagnachmittag (14. Juli) kam es zu einem Gro\u00dfeinsatz: Zun\u00e4chst wurde die Feuerwehr Iserlohn gegen 16 Uhr wegen eines Waldbrandes zwischen Iserlohn-Letmathe und Nachrodt-Wiblingwerde gerufen. In der Hanglage breitete sich das Feuer rasant aus. Es brannte auf einer Fl\u00e4che von 10.000 Quadratmetern unwegsamen Gel\u00e4ndes. Die Rauchs\u00e4ule war weithin bis nach Hagen sichtbar<\/p>\n<p><strong>NINA-Warnung ausgel\u00f6st<\/strong><\/p>\n<p>Aufgrund der sehr hohen Rauchentwicklung und der Geruchsbel\u00e4stigung wurde kurzzeitig eine NIINA-Warnung ausgel\u00f6st. Es wurden weitere Einheiten hinzualarmiert: Im Einsatz waren die gesamte Feuerwehr Iserlohn, ein vorgeplanter Wassertransportzug der Feuerwehren aus Menden, Hemer, Neuenrade und Balve sowie die \u00fcber\u00f6rtlichen L\u00f6schz\u00fcge aus Menden und L\u00fcdenscheid. Aus Nachrodt-Wiblingwerde r\u00fcckte die Feuerwehr mit der Drohneneinheit MK, einem L\u00f6schfahrzeug sowie einem speziell f\u00fcr die Rettung von Personen aus unwegsamem Gel\u00e4nde ausger\u00fcsteten Pickup an. Der Kreisbrandmeister Michael Kling und zwei Fahrzeuge des Brandschutz- und Rettungsdienstzentrums des Kreises waren vor Ort. Das THW Iserlohn unterst\u00fctze am Abend mit einem Notstromaggregat und Beleuchtung. F\u00fcr reibungslose An- und Abfahrten sorgte die Polizei mit Stra\u00dfensperrungen. Die Verpflegung und Betreuung \u00fcbernahmen das Deutsche Rote Kreuz Iserlohn.<\/p>\n<p><strong>250 Kr\u00e4fte im Einsatz<\/strong><\/p>\n<p>\u201eInsgesamt waren rund 250 Einsatzkr\u00e4fte vor Ort im Einsatz\u201c, berichtet Kreisbrandmeister Michael Kling. Ein angeforderter Hubschrauber, der Wasser abwerfen sollte, konnte nicht zum Einsatz kommen, weil die Brandfl\u00e4che unter den Hochspannungsleitungen lag. Um eine m\u00f6gliche notwendige Abschaltung der Hochspannungstrasse zu erkunden und zu beraten, wurden Mitarbeiter der Firma Amprion hinzugezogen. Die Drohneneinheit lieferte Live-Bilder zur Erkundung und zwei Experten von Wald und Holz waren als st\u00e4ndige Ansprechpartner vor Ort.<\/p>\n<p><strong>Wasserversorgung im Pendelverkehr<\/strong><\/p>\n<p>Die Wasserversorgung f\u00fcr das Gebiet wurde mittels Pendelverkehrs mit Fahrzeugen sowie einer Schlauchleitung aus der Ortschaft Deierte hergestellt. Mit Hilfe eines Forstmulchers (einer Art Bodenfr\u00e4se) konnte eine Schneise in einer Breite von etwa drei Metern in die Birkendickung gezogen werden. \u201eIn dieser Schneise wurden anschlie\u00dfend die Kreisregner installiert und somit eine vollst\u00e4ndige Riegelstellung aufgebaut\u201c, erkl\u00e4rt Michael Kling. Eine weitere Ausbreitung konnte so am Abend gestoppt und die Brandstellen auf der Fl\u00e4che abgel\u00f6scht werden. Der Einsatz dauerte bis in den Mittwochmorgen (15. Juli).<\/p>\n<p><strong>Positive Einsatz-Bilanz<\/strong><\/p>\n<p>Kreisbrandmeister Michael Kling zieht insgesamt eine positive Bilanz des Einsatzes: \u201eDieser Einsatz hat eindrucksvoll gezeigt, wie sich die Feuerwehren gemeinsam mit dem M\u00e4rkischen Kreis in den vergangenen Jahren intensiv auf Vegetationsbr\u00e4nde eingestellt haben.\u00a0 Die Vorplanung von Einheiten f\u00fcr bestimmte F\u00e4higkeiten (Wassertransport, Vegetationsbrandbek\u00e4mpfung, Erkundung, Logistik) haben sich bestens bew\u00e4hrt und unterst\u00fctzen die Feuerwehren bei ihrer Aufgabe der Gefahrenabwehr.\u201c<\/p>\n<p><strong>Neue Ausr\u00fcstung eingesetzt<\/strong><\/p>\n<p>So konnte die vom M\u00e4rkischen Kreis in den vergangenen Jahren beschaffte Ausr\u00fcstung f\u00fcr Vegetationsbr\u00e4nde erfolgreich zum Einsatz gebracht werden &#8211; unter anderem zwei L\u00f6schwasserbeh\u00e4lter mit je 35.000 Liter und 15.000 Litern Fassungsverm\u00f6gen, L\u00f6schrucks\u00e4cke, Handwerkzeug, die Kreisregner, spezielle Rucks\u00e4cke mit Schlauchmaterial und Strahlrohren f\u00fcr die Vegetationsbrandbek\u00e4mpfung einem Fahrzeug zum Transport von 10.000 Litern L\u00f6schwasser, zwei gel\u00e4ndef\u00e4hige Fahrzeuge und auch ein Anh\u00e4nger mit zwei Toiletten.<\/p>\n<p><strong>Dank an alle Einsatzkr\u00e4fte<\/strong><\/p>\n<p>Kling bedankte sich ausdr\u00fccklich bei allen Einsatzkr\u00e4ften, die vor Ort im Einsatz waren oder im Hintergrund f\u00fcr den reibungslosen Ablauf gesorgt haben: \u201eTrotz der hohen Temperaturen und des sehr schwierigen Gel\u00e4ndes haben die Feuerwehren auf der Brandfl\u00e4che hervorragende Arbeit geleistet.\u201c<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kreisbrandmeister: &#8222;Gute Vorbereitung hat sich ausgezahlt&#8220; (pmk). Das anhaltend hei\u00dfe  [&#8230;]<\/p>\n","protected":false},"author":3,"featured_media":27090,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"footnotes":""},"categories":[3],"tags":[],"class_list":["post-27089","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-polizeimeldungen"],"_links":{"self":[{"href":"https:\/\/www.mk-journal.de\/index.php\/wp-json\/wp\/v2\/posts\/27089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mk-journal.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mk-journal.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mk-journal.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mk-journal.de\/index.php\/wp-json\/wp\/v2\/comments?post=27089"}],"version-history":[{"count":1,"href":"https:\/\/www.mk-journal.de\/index.php\/wp-json\/wp\/v2\/posts\/27089\/revisions"}],"predecessor-version":[{"id":27091,"href":"https:\/\/www.mk-journal.de\/index.php\/wp-json\/wp\/v2\/posts\/27089\/revisions\/27091"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mk-journal.de\/index.php\/wp-json\/wp\/v2\/media\/27090"}],"wp:attachment":[{"href":"https:\/\/www.mk-journal.de\/index.php\/wp-json\/wp\/v2\/media?parent=27089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mk-journal.de\/index.php\/wp-json\/wp\/v2\/categories?post=27089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mk-journal.de\/index.php\/wp-json\/wp\/v2\/tags?post=27089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}